{"id":1195,"date":"2025-10-20T10:10:42","date_gmt":"2025-10-20T08:10:42","guid":{"rendered":"https:\/\/laukiarkitektura.eus\/proyecto\/hab-paisaiagintza-eta-turismoa\/"},"modified":"2026-04-01T08:27:48","modified_gmt":"2026-04-01T06:27:48","slug":"hab-paisajismo-y-turismo","status":"publish","type":"proyecto","link":"https:\/\/laukiarkitektura.eus\/es\/proyecto\/hab-paisajismo-y-turismo\/","title":{"rendered":"HAB &#8211; Paisajismo y turismo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 nos encontramos?<\/strong><\/h2>\n\n\n\n<p>El Ayuntamiento de Deba, en colaboraci\u00f3n con el Geoparque, quer\u00eda llevar a cabo un proyecto para crear una ruta sobre la prehistoria. Para ello, era necesario analizar cuidadosamente el impacto de los recursos f\u00edsicos que se iban a emplear, con el fin de integrarlos de manera arm\u00f3nica en el paisaje de Deba, tanto urbano como natural. El objetivo del proyecto era lograr una conexi\u00f3n respetuosa con el medio ambiente y el entorno paisaj\u00edstico, promoviendo el conocimiento de la prehistoria y ofreciendo una experiencia enriquecedora a los visitantes, sin poner en riesgo la conservaci\u00f3n del entorno.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 hicimos?<\/strong><\/h2>\n\n\n\n<p>En el proyecto HAB (Historiaurreko Bailara \/ Valle de la prehistoria) se conectan la costa y la zona monta\u00f1osa de Deba mediante una ruta dedicada a la prehistoria, mostrando la profunda relaci\u00f3n entre el pasado hist\u00f3rico y el entorno natural del lugar.<\/p>\n\n\n\n<p>A lo largo del recorrido se narra la historia de los Neandertales y de los Homo sapiens que habitaron esta zona entre hace 200.000 y 15.000 a\u00f1os, describiendo la evoluci\u00f3n del clima, la fauna y la flora de aquellas \u00e9pocas. En los paneles dise\u00f1ados a lo largo de la ruta se explica el trabajo de los arque\u00f3logos y se incluyen r\u00e9plicas de los restos encontrados en la zona. Estas r\u00e9plicas, producidas mediante tecnolog\u00edas avanzadas, permiten acercar a todos el conocimiento y la puesta en valor de nuestro pasado m\u00e1s pr\u00f3ximo.<\/p>\n\n\n\n<p>El proyecto promueve un turismo sostenible, en coherencia con la conservaci\u00f3n del paisaje y el medio ambiente, buscando el equilibrio entre cultura y naturaleza.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":2025,"template":"","meta":{"_acf_changed":false},"class_list":["post-1195","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/proyecto\/1195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/types\/proyecto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/media\/2025"}],"wp:attachment":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/media?parent=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}