{"id":1235,"date":"2025-10-16T17:34:25","date_gmt":"2025-10-16T15:34:25","guid":{"rendered":"https:\/\/laukiarkitektura.eus\/proyecto\/aizarna-kortxoarekin-eraberritzen\/"},"modified":"2026-03-31T15:15:57","modified_gmt":"2026-03-31T13:15:57","slug":"aizarna-rehabilitando-con-corcho","status":"publish","type":"proyecto","link":"https:\/\/laukiarkitektura.eus\/es\/proyecto\/aizarna-rehabilitando-con-corcho\/","title":{"rendered":"AIZARNA &#8211; Rehabilitando con corcho"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 nos encontramos?<\/h2>\n\n\n\n<p>El tejado presentaba filtraciones desde su construcci\u00f3n y a lo largo de los a\u00f1os no se hab\u00eda conseguido resolver el problema. Al analizar el proyecto original del edificio, comprobamos que el error proven\u00eda del propio dise\u00f1o constructivo.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 hicimos?<\/h2>\n\n\n\n<p>En la construcci\u00f3n de la antigua cubierta se hab\u00eda utilizado un sistema constructivo inadecuado: los rastreles estaban colocados al rev\u00e9s. Cada vez que llov\u00eda, el agua se acumulaba entre ellos y se filtraba al interior de la vivienda, provocando da\u00f1os. Para solucionar el problema, ha sido necesario rehacer completamente el tejado.<\/p>\n\n\n\n<p>El cliente, consciente del consumo y del impacto ambiental que generan las obras, nos pidi\u00f3 una propuesta sostenible para la rehabilitaci\u00f3n de la cubierta. Tras realizar los c\u00e1lculos de transmitancia y condensaciones, decidimos utilizar aislamiento t\u00e9rmico de corcho, sin barrera de vapor, por sus propiedades higrosc\u00f3picas e impermeables. El corcho es un material natural, renovable, imputrescible, ecol\u00f3gico y con un excelente comportamiento aislante.<\/p>\n\n\n\n<p>La nueva cubierta se ha ejecutado cumpliendo las exigencias t\u00e9rmicas actuales: se ha aislado t\u00e9rmicamente con placas de corcho y se ha colocado una l\u00e1mina impermeable y transpirable para evitar condensaciones y mantener la estructura de madera en un nivel \u00f3ptimo de humedad.<\/p>\n\n\n\n<p>Durante la demolici\u00f3n del tejado se desmontaron las tejas y los antiguos paneles de poliestireno, que el cliente decidi\u00f3 donar como material de segunda mano. Este proyecto nos ha recordado que existe otra manera de construir, reduciendo al m\u00e1ximo el impacto ecol\u00f3gico de la edificaci\u00f3n mediante una gesti\u00f3n circular de los residuos y la elecci\u00f3n de materiales naturales.<\/p>\n","protected":false},"featured_media":1949,"template":"","meta":{"_acf_changed":true},"class_list":["post-1235","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/proyecto\/1235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/types\/proyecto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/media\/1949"}],"wp:attachment":[{"href":"https:\/\/laukiarkitektura.eus\/es\/wp-json\/wp\/v2\/media?parent=1235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}